{"id":132220,"date":"2025-04-15T01:15:41","date_gmt":"2025-04-15T08:15:41","guid":{"rendered":"https:\/\/www.vertigis.com\/?post_type=customer_story&#038;p=132220"},"modified":"2025-12-01T07:07:49","modified_gmt":"2025-12-01T15:07:49","slug":"stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis","status":"publish","type":"customer_story","link":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/","title":{"rendered":"Stadtwerke W\u00f6rgl automatisieren Prozesse mit ConnectMaster von VertiGIS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Modernste Software unterst\u00fctzt bei der Dokumentation des Glasfasernetzes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insbesondere kleinere Telekommunikationsanbieter stehen vor der immensen Herausforderung, trotz zunehmend kritischerer personeller Ressourcen immer schneller auf stetig steigende Anforderungen bei der Verwaltung ihrer Netze reagieren zu m\u00fcssen. Um einen m\u00f6glichst hohen Grad an Automatisierung und Effizienz zu erreichen, ist der Einsatz professioneller und modernster Technologien bei der Netzdokumentation und -verwaltung unabdingbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Herausforderung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch f\u00fcr die Stadtwerke W\u00f6rgl war klar, dass an einer state-of-the-art Software kein Weg vorbeif\u00fchrt. Die Stadtwerke versorgen die 15.000 Einwohnerinnen und Einwohner nicht nur mit Strom und Wasser, sondern sind auch Internet-Service Provider f\u00fcr Endkunden. Dazu errichten und betreiben die Stadtwerke das Glasfasernetz. Wie viele andere Unternehmen standen auch die Stadtwerke vor der Herausforderung, eine umfassende Dokumentation des Bestandsnetzes sowie die Planung von Netzerweiterungen mit den verf\u00fcgbaren Ressourcen m\u00f6glichst effizient und dennoch genau umzusetzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u00f6sung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In einem ersten Schritt entschieden sich die Stadtwerke W\u00f6rgl, zun\u00e4chst das Glasfasernetz umfassend zu dokumentieren. Mit <a href=\"https:\/\/www.vertigis.com\/de\/connectmaster\/\"><strong>VertiGIS ConnectMaster<\/strong><\/a> ist es gelungen, erstmals eine vollst\u00e4ndige Netzdokumentation zu erreichen. Dabei erfasst das Telco-Team der Stadtwerke alle passiven und aktiven Komponenten des physischen Netzes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die vollst\u00e4ndige Netzdokumentation wird nun fortlaufend um Netzerweiterungen erg\u00e4nzt. Um die Daten einem erweiterten Kreis zur Verf\u00fcgung stellen zu k\u00f6nnen, haben die Stadtwerke W\u00f6rgl ihre ConnectMaster Produktsuite zuletzt um <strong>ConnectMaster Online<\/strong> erg\u00e4nzt. Der Web-Client erm\u00f6glicht es, Informationen oder technische Daten zum und aus dem Netz \u00fcber mobile Endger\u00e4te intuitiv und einfach abzurufen oder zu erfassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Resultat<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Stadtwerke W\u00f6rgl haben ihr Ziel, Arbeitsprozesse effizienter und somit kosteng\u00fcnstiger zu gestalten, vollst\u00e4ndig erreicht. Schrittweise konnten wiederkehrende T\u00e4tigkeiten mit ConnectMaster automatisiert oder die Erfassung von Informationen stark vereinfacht werden. Dies spart den Verantwortlichen jede Menge Zeit, die nun f\u00fcr andere Aufgaben zur Verf\u00fcgung steht. Zugleich verf\u00fcgen die Stadtwerke W\u00f6rgl nun \u00fcber einen konsistenten Datensatz, der mit geringem Aufwand gepflegt und erweitert werden kann. So kann das Team erheblich effizienter arbeiten und hat freie Ressourcen f\u00fcr wichtige Themen wieschnelle Fehlersuche bekommen. &nbsp;Alle notwendigen Informationen stehen mit wenigen Klicks bereit \u2013 umst\u00e4ndliche R\u00fcckfragen entfallen vollst\u00e4ndig. Fehler k\u00f6nnen so schneller erfasst und behoben werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Telco-Team der Stadtwerke W\u00f6rgl ist mit dem Ergebnis sehr zufrieden: \u201eWir arbeiten in einem kleinen Team hochprofessionell. F\u00fcr uns ist es sehr wichtig, dass unsere Daten aktuell und vollst\u00e4ndig sind. Dies gelingt mit ConnectMaster von VertiGIS sehr gut. Die Software l\u00e4sst sich einfach bedienen und ist daher aus unseren allt\u00e4glichen Prozessen nicht mehr wegzudenken\u201c, sagt Martin Koidl, Teamleitung NT Services bei den Stadtwerken W\u00f6rgl.<\/p>\n","protected":false},"featured_media":132224,"parent":0,"template":"","tags":[],"customer_industry":[121],"customer_products":[368],"class_list":["post-132220","customer_story","type-customer_story","status-publish","has-post-thumbnail","hentry","customer_industry-telekommunikation","customer_products-connectmaster-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stadtwerke W\u00f6rgl optimieren Glasfasernetz-Prozesse<\/title>\n<meta name=\"description\" content=\"Stadtwerke W\u00f6rgl dokumentieren Glasfasernetze und automatisieren Prozesse \u2013 f\u00fcr effiziente Abl\u00e4ufe und digitale Transformation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stadtwerke W\u00f6rgl automatisieren Prozesse mit ConnectMaster von VertiGIS\" \/>\n<meta property=\"og:description\" content=\"Modernste Software unterst\u00fctzt bei der Dokumentation des Glasfasernetzes Insbesondere kleinere Telekommunikationsanbieter stehen vor der immensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/\" \/>\n<meta property=\"og:site_name\" content=\"VertiGIS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T15:07:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/04\/AdobeStock_686831645-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/\",\"name\":\"Stadtwerke W\u00f6rgl optimieren Glasfasernetz-Prozesse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/AdobeStock_686831645-scaled.jpeg\",\"datePublished\":\"2025-04-15T08:15:41+00:00\",\"dateModified\":\"2025-12-01T15:07:49+00:00\",\"description\":\"Stadtwerke W\u00f6rgl dokumentieren Glasfasernetze und automatisieren Prozesse \u2013 f\u00fcr effiziente Abl\u00e4ufe und digitale Transformation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/AdobeStock_686831645-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/AdobeStock_686831645-scaled.jpeg\",\"width\":2560,\"height\":1434},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Customer Stories\",\"item\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/customers\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stadtwerke W\u00f6rgl automatisieren Prozesse mit ConnectMaster von VertiGIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/\",\"name\":\"VertiGIS\",\"description\":\"Enterprise spatial asset management solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#organization\",\"name\":\"VertiGIS\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/VertiGIS-Studio-Logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/VertiGIS-Studio-Logo-1-1.png\",\"width\":823,\"height\":127,\"caption\":\"VertiGIS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stadtwerke W\u00f6rgl optimieren Glasfasernetz-Prozesse","description":"Stadtwerke W\u00f6rgl dokumentieren Glasfasernetze und automatisieren Prozesse \u2013 f\u00fcr effiziente Abl\u00e4ufe und digitale Transformation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/","og_locale":"de_DE","og_type":"article","og_title":"Stadtwerke W\u00f6rgl automatisieren Prozesse mit ConnectMaster von VertiGIS","og_description":"Modernste Software unterst\u00fctzt bei der Dokumentation des Glasfasernetzes Insbesondere kleinere Telekommunikationsanbieter stehen vor der immensen","og_url":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/","og_site_name":"VertiGIS","article_modified_time":"2025-12-01T15:07:49+00:00","og_image":[{"width":2560,"height":1434,"url":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/04\/AdobeStock_686831645-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/","url":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/","name":"Stadtwerke W\u00f6rgl optimieren Glasfasernetz-Prozesse","isPartOf":{"@id":"https:\/\/www.vertigis.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/#primaryimage"},"image":{"@id":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/04\/AdobeStock_686831645-scaled.jpeg","datePublished":"2025-04-15T08:15:41+00:00","dateModified":"2025-12-01T15:07:49+00:00","description":"Stadtwerke W\u00f6rgl dokumentieren Glasfasernetze und automatisieren Prozesse \u2013 f\u00fcr effiziente Abl\u00e4ufe und digitale Transformation.","breadcrumb":{"@id":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/#primaryimage","url":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/04\/AdobeStock_686831645-scaled.jpeg","contentUrl":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/04\/AdobeStock_686831645-scaled.jpeg","width":2560,"height":1434},{"@type":"BreadcrumbList","@id":"https:\/\/www.vertigis.com\/de\/customers\/stadtwerke-woergl-automatisieren-prozesse-mit-connectmaster-von-vertigis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Customer Stories","item":"https:\/\/www.vertigis.com\/de\/customers\/"},{"@type":"ListItem","position":2,"name":"Stadtwerke W\u00f6rgl automatisieren Prozesse mit ConnectMaster von VertiGIS"}]},{"@type":"WebSite","@id":"https:\/\/www.vertigis.com\/de\/#website","url":"https:\/\/www.vertigis.com\/de\/","name":"VertiGIS","description":"Enterprise spatial asset management solutions","publisher":{"@id":"https:\/\/www.vertigis.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vertigis.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vertigis.com\/de\/#organization","name":"VertiGIS","url":"https:\/\/www.vertigis.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vertigis.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/07\/VertiGIS-Studio-Logo-1-1.png","contentUrl":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/07\/VertiGIS-Studio-Logo-1-1.png","width":823,"height":127,"caption":"VertiGIS"},"image":{"@id":"https:\/\/www.vertigis.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/customer_story\/132220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/customer_story"}],"about":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/types\/customer_story"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/media\/132224"}],"wp:attachment":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/media?parent=132220"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/tags?post=132220"},{"taxonomy":"customer_industry","embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/customer_industry?post=132220"},{"taxonomy":"customer_products","embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/customer_products?post=132220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}