{"id":11165,"date":"2023-01-31T03:14:36","date_gmt":"2023-01-31T11:14:36","guid":{"rendered":"https:\/\/www.vertigis.com\/?post_type=vertigis_blog&#038;p=11165"},"modified":"2025-12-01T06:04:09","modified_gmt":"2025-12-01T14:04:09","slug":"nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen","status":"publish","type":"vertigis_blog","link":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/","title":{"rendered":"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Planen Sie den Einsatz einer CAFM-Software, um Ihre Arbeitsabl\u00e4ufe effizienter zu gestalten? F\u00fcr einen langfristigen Erfolg und eine hohe Akzeptanz in Ihrem Team sollten Sie eine daf\u00fcr geeignete Software ausw\u00e4hlen. Die folgenden Fragen helfen Ihnen, die wichtigsten Kriterien zu ber\u00fccksichtigen:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>In welchen Arbeitsbereichen ist die CAFM-Software potenziell einsetzbar?<\/em><br><\/strong>Viele unserer Kunden starten mit der Umsetzung einer spezifischen Aufgabenstellung und m\u00f6chten den Softwareeinsatz aufgrund positiver R\u00fcckmeldungen im Lauf der Zeit erweitern. Evaluieren Sie das gesamte Aufgabenspektrum in Ihrer Organisation, welches f\u00fcr CAFM geeignet ist (z. B. Management von Assets aller Art wie Geb\u00e4ude, Grundst\u00fccke, Anlagen, Gr\u00fcnfl\u00e4chen, Vertr\u00e4ge, Fuhrparks, Beleuchtungsanlagen und damit verbundene Abl\u00e4ufe wie Instandhaltungen, Ressourcenmonitoring, Kostenabrechnungen, Reinigungen\/Pflege, Zeiterfassungen oder Vermietungen). Suchen Sie danach von Anfang an nach einer zentralen Software-Plattform, welche s\u00e4mtliche Aufgaben abdeckt, anstatt aufwendig Einzell\u00f6sungen einzuf\u00fchren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Wie wurde die Software technisch umgesetzt?<\/em><br><\/strong>Eine moderne, einfach zu bedienbare Software bedeutet in der Praxis: keine langen Einschulungen, keine unn\u00f6tigen Hardwarebeschaffungen oder aufwendige Software-Installationen. Achten Sie daher darauf, dass die Software technisch auf dem neuesten Stand ist, also laufend den aktuellen IT-Systemen angepasst wird, dass s\u00e4mtliche Daten zentral gehostet werden und eine intuitive, ger\u00e4teunabh\u00e4ngige Bedienung am Desktop PC, Tablet und Smartphone m\u00f6glich ist. Je nach Datenschutzanforderungen sollten Sie Ihre Daten flexibel in einer vom Hersteller gewarteten Cloud hosten oder auf Ihrem eigenen Server betreiben k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Gibt es eine Unterst\u00fctzung bei der Dateneingabe und Anbindung von Drittsystemen?<\/em><br><\/strong>Der Aufwand f\u00fcr eine Dateneingabe oder eine Migration bestehender Daten ist nicht zu untersch\u00e4tzen. Wenn Ihre Software diese Prozesse optimal abdeckt, gelingen auch die damit verbundenen Arbeiten im Handumdrehen. Achten Sie daher auf praxiserprobte Prozess- und Objektstrukturen, z. B. vordefinierte Abl\u00e4ufe oder Auswahllisten mit typischen Objekteigenschaften. Der Import bestehender Daten sollte einfach m\u00f6glich sein und Drittsysteme sollten Sie \u00fcber flexible Schnittstellen anbinden k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Wie wird die Zusammenarbeit gesteuert?<\/em><br><\/strong>Ihre Mitarbeitenden m\u00f6chten sich in der Regel auf die f\u00fcr sie relevanten Aufgaben fokussieren. Achten Sie darauf, dass Ihre CAFM-Software ein gut durchdachtes Rollen- und Rechtekonzept aufweist, mit dem Sie nicht nur Zust\u00e4ndigkeiten klar definieren, sondern auch die Zugriffsrechte bis ins Detail festlegen k\u00f6nnen. So sorgen Sie f\u00fcr maximale \u00dcbersichtlichkeit und garantieren die Einhaltung der Datenschutzvorgaben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Werden die Daten anschaulich pr\u00e4sentiert?<\/em><br><\/strong>Komplexe Zusammenh\u00e4nge und Trends erkennen Sie am besten mit aussagekr\u00e4ftigen Grafiken, Diagrammen, Karten und\/oder Pl\u00e4nen. Achten Sie daher auf moderne Analysewerkzeuge, umfangreiche Visualisierungsm\u00f6glichkeiten und eine Anbindung von BIM-Pl\u00e4nen sowie GIS-Karten in 2D und 3D. Hochwertige Berichtsvorlagen helfen Ihnen, erzielte Erfolge mit geringem Aufwand ansprechend zu pr\u00e4sentieren.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"546\" src=\"https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-1024x546.jpg\" alt=\"\" class=\"wp-image-11169\" srcset=\"https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-1024x546.jpg 1024w, https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-300x160.jpg 300w, https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-1536x820.jpg 1536w, https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-2048x1093.jpg 2048w, https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-400x213.jpg 400w, https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-800x427.jpg 800w, https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-1200x640.jpg 1200w, https:\/\/www.vertigis.com\/wp-content\/uploads\/2023\/01\/Screens-Pressemitteilung_RGBneu-1600x854.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Eine moderne CAFM Software funktioniert ger\u00e4teunabh\u00e4ngig und bietet aussagekr\u00e4ftige Visualisierungsm\u00f6glichkeiten wie Diagramme, Karten und Pl\u00e4ne<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u00dcber welches Lizenzmodell werden die Kosten abgerechnet?<\/strong><\/em><br>Als Nutzer*in einer CAFM-Software sollten Sie nur f\u00fcr das bezahlen, was Sie tats\u00e4chlich ben\u00f6tigen. Nehmen Sie ein flexibles Lizenzmodell in Anspruch, dass sich an der Anzahl der Anwender*innen und den ben\u00f6tigten Arbeitsbereichen orientiert. Achten Sie darauf, dass regelm\u00e4\u00dfige Updates in Ihrem Lizenzmodell inkludiert sind, sodass Sie Ihren Mitarbeitenden mit gutem Gewissen eine maximale Sicherheit garantieren k\u00f6nnen. Falls Fragen auftauchen oder Hilfe bei der Projektumsetzung ben\u00f6tigt wird, sollte ein langfristiges Supportangebot in jedem Fall inkludiert sein. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Konnten wir Sie von dem Einsatz einer modernen CAFM-Software \u00fcberzeugen? Dann schauen Sie sich unser <a href=\"https:\/\/www.vertigis.com\/de\/vertigis-fm\/\">L\u00f6sungsportfolio<\/a>&nbsp;an und <a href=\"https:\/\/www.vertigis.com\/de\/kontaktieren-sie-uns\/\">kontaktieren Sie uns<\/a>. Wir beraten Sie gerne bei der Einf\u00fchrung einer f\u00fcr Sie optimalen CAFM-L\u00f6sung!<br><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><\/div>\n","protected":false},"featured_media":9382,"parent":0,"template":"","tags":[],"blog_industry":[123,131,132,134],"blog_products":[370],"class_list":["post-11165","vertigis_blog","type-vertigis_blog","status-publish","has-post-thumbnail","hentry","blog_industry-infrastruktur","blog_industry-offentliche-verwaltung","blog_industry-telekommunikation","blog_industry-utilities-de","blog_products-vertigis-fm-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen<\/title>\n<meta name=\"description\" content=\"So w\u00e4hlen Sie die richtige CAFM-Software: Wichtige Kriterien und Tipps f\u00fcr ein effizientes, zukunftssicheres Facility Management.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen\" \/>\n<meta property=\"og:description\" content=\"Planen Sie den Einsatz einer CAFM-Software, um Ihre Arbeitsabl\u00e4ufe effizienter zu gestalten? F\u00fcr einen langfristigen Erfolg und eine hohe Akzeptanz in\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/\" \/>\n<meta property=\"og:site_name\" content=\"VertiGIS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T14:04:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vertigis.com\/wp-content\/uploads\/2022\/12\/AdobeStock_493922552-1024x683.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/\",\"name\":\"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/AdobeStock_493922552.jpeg\",\"datePublished\":\"2023-01-31T11:14:36+00:00\",\"dateModified\":\"2025-12-01T14:04:09+00:00\",\"description\":\"So w\u00e4hlen Sie die richtige CAFM-Software: Wichtige Kriterien und Tipps f\u00fcr ein effizientes, zukunftssicheres Facility Management.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/AdobeStock_493922552.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/AdobeStock_493922552.jpeg\",\"width\":8192,\"height\":5464},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Posts\",\"item\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/vertigis_blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/\",\"name\":\"VertiGIS\",\"description\":\"Enterprise spatial asset management solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#organization\",\"name\":\"VertiGIS\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/VertiGIS-Studio-Logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vertigis.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/VertiGIS-Studio-Logo-1-1.png\",\"width\":823,\"height\":127,\"caption\":\"VertiGIS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vertigis.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen","description":"So w\u00e4hlen Sie die richtige CAFM-Software: Wichtige Kriterien und Tipps f\u00fcr ein effizientes, zukunftssicheres Facility Management.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/","og_locale":"de_DE","og_type":"article","og_title":"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen","og_description":"Planen Sie den Einsatz einer CAFM-Software, um Ihre Arbeitsabl\u00e4ufe effizienter zu gestalten? F\u00fcr einen langfristigen Erfolg und eine hohe Akzeptanz in","og_url":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/","og_site_name":"VertiGIS","article_modified_time":"2025-12-01T14:04:09+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2022\/12\/AdobeStock_493922552-1024x683.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/","url":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/","name":"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen","isPartOf":{"@id":"https:\/\/www.vertigis.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/#primaryimage"},"image":{"@id":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2022\/12\/AdobeStock_493922552.jpeg","datePublished":"2023-01-31T11:14:36+00:00","dateModified":"2025-12-01T14:04:09+00:00","description":"So w\u00e4hlen Sie die richtige CAFM-Software: Wichtige Kriterien und Tipps f\u00fcr ein effizientes, zukunftssicheres Facility Management.","breadcrumb":{"@id":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/#primaryimage","url":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2022\/12\/AdobeStock_493922552.jpeg","contentUrl":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2022\/12\/AdobeStock_493922552.jpeg","width":8192,"height":5464},{"@type":"BreadcrumbList","@id":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/nach-diesen-kriterien-sollten-sie-ihre-cafm-software-auswaehlen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Posts","item":"https:\/\/www.vertigis.com\/de\/vertigis_blog\/"},{"@type":"ListItem","position":2,"name":"Nach diesen Kriterien sollten Sie Ihre CAFM-Software ausw\u00e4hlen"}]},{"@type":"WebSite","@id":"https:\/\/www.vertigis.com\/de\/#website","url":"https:\/\/www.vertigis.com\/de\/","name":"VertiGIS","description":"Enterprise spatial asset management solutions","publisher":{"@id":"https:\/\/www.vertigis.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vertigis.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vertigis.com\/de\/#organization","name":"VertiGIS","url":"https:\/\/www.vertigis.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vertigis.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/07\/VertiGIS-Studio-Logo-1-1.png","contentUrl":"https:\/\/www.vertigis.com\/wp-content\/uploads\/2025\/07\/VertiGIS-Studio-Logo-1-1.png","width":823,"height":127,"caption":"VertiGIS"},"image":{"@id":"https:\/\/www.vertigis.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/vertigis_blog\/11165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/vertigis_blog"}],"about":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/types\/vertigis_blog"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/media\/9382"}],"wp:attachment":[{"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/media?parent=11165"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/tags?post=11165"},{"taxonomy":"blog_industry","embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/blog_industry?post=11165"},{"taxonomy":"blog_products","embeddable":true,"href":"https:\/\/www.vertigis.com\/de\/wp-json\/wp\/v2\/blog_products?post=11165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}